{"id":10990,"date":"2023-06-23T08:34:29","date_gmt":"2023-06-23T01:34:29","guid":{"rendered":"https:\/\/ptl.ac.th\/web\/?p=10990"},"modified":"2023-06-23T08:34:29","modified_gmt":"2023-06-23T01:34:29","slug":"10990","status":"publish","type":"post","link":"https:\/\/ptl.ac.th\/web\/2023\/06\/23\/10990\/","title":{"rendered":""},"content":{"rendered":"\n<p>\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35 \u0e17\u0e35\u0e48 22  \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2566 \u0e19\u0e32\u0e22\u0e18\u0e19\u0e34\u0e15 \u0e41\u0e17\u0e48\u0e19\u0e1b\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e23\u0e39 \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2d\u0e14\u0e35\u0e15\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e04\u0e23\u0e39\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e41\u0e02\u0e01\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e44\u0e2b\u0e27\u0e49\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e27\u0e07\u0e2a\u0e23\u0e27\u0e07\u0e1a\u0e39\u0e0a\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e27\u0e34\u0e29\u0e13\u0e38\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2566 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e16\u0e37\u0e2d\u0e1e\u0e32\u0e19\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e18\u0e39\u0e1b\u0e40\u0e17\u0e35\u0e22\u0e19\u0e04\u0e32\u0e23\u0e32\u0e27\u0e30\u0e04\u0e38\u0e13\u0e04\u0e23\u0e39 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e30\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\u0e17\u0e35\u0e48\u0e2d\u0e1a\u0e23\u0e21\u0e2a\u0e31\u0e48\u0e07\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e27\u0e34\u0e0a\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e01\u0e48\u0e28\u0e34\u0e29\u0e22\u0e4c \u0e13 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/2-11-1024x683.jpg\" alt=\"\" data-id=\"10991\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/2-11.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10991\" class=\"wp-image-10991\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/2-11-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/2-11-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/2-11-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/2-11-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/2-11.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/3-10-1024x683.jpg\" alt=\"\" data-id=\"10992\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/3-10.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10992\" class=\"wp-image-10992\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/3-10-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/3-10-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/3-10-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/3-10-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/3-10.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/4-10-1024x683.jpg\" alt=\"\" data-id=\"10993\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/4-10.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10993\" class=\"wp-image-10993\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/4-10-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/4-10-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/4-10-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/4-10-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/4-10.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/5-9-1024x683.jpg\" alt=\"\" data-id=\"10994\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/5-9.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10994\" class=\"wp-image-10994\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/5-9-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/5-9-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/5-9-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/5-9-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/5-9.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/6-9-1024x683.jpg\" alt=\"\" data-id=\"10995\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/6-9.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10995\" class=\"wp-image-10995\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/6-9-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/6-9-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/6-9-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/6-9-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/6-9.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/7-9-1024x683.jpg\" alt=\"\" data-id=\"10996\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/7-9.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10996\" class=\"wp-image-10996\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/7-9-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/7-9-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/7-9-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/7-9-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/7-9.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/8-9-1024x683.jpg\" alt=\"\" data-id=\"10997\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/8-9.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10997\" class=\"wp-image-10997\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/8-9-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/8-9-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/8-9-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/8-9-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/8-9.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/9-9-1024x683.jpg\" alt=\"\" data-id=\"10998\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/9-9.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10998\" class=\"wp-image-10998\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/9-9-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/9-9-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/9-9-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/9-9-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/9-9.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/10-8-1024x683.jpg\" alt=\"\" data-id=\"10999\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/10-8.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=10999\" class=\"wp-image-10999\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/10-8-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/10-8-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/10-8-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/10-8-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/10-8.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/11-6-1024x683.jpg\" alt=\"\" data-id=\"11000\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/11-6.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11000\" class=\"wp-image-11000\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/11-6-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/11-6-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/11-6-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/11-6-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/11-6.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/12-6-1024x683.jpg\" alt=\"\" data-id=\"11001\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/12-6.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11001\" class=\"wp-image-11001\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/12-6-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/12-6-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/12-6-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/12-6-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/12-6.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/13-5-1024x683.jpg\" alt=\"\" data-id=\"11002\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/13-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11002\" class=\"wp-image-11002\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/13-5-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/13-5-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/13-5-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/13-5-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/13-5.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/14-5-1024x683.jpg\" alt=\"\" data-id=\"11003\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/14-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11003\" class=\"wp-image-11003\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/14-5-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/14-5-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/14-5-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/14-5-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/14-5.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/15-5-1024x683.jpg\" alt=\"\" data-id=\"11004\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/15-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11004\" class=\"wp-image-11004\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/15-5-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/15-5-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/15-5-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/15-5-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/15-5.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/16-5-1024x683.jpg\" alt=\"\" data-id=\"11005\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/16-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11005\" class=\"wp-image-11005\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/16-5-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/16-5-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/16-5-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/16-5-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/16-5.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/17-4-1024x683.jpg\" alt=\"\" data-id=\"11006\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/17-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11006\" class=\"wp-image-11006\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/17-4-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/17-4-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/17-4-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/17-4-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/17-4.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/18-4-1024x683.jpg\" alt=\"\" data-id=\"11007\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/18-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11007\" class=\"wp-image-11007\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/18-4-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/18-4-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/18-4-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/18-4-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/18-4.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/19-4-1024x683.jpg\" alt=\"\" data-id=\"11008\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/19-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11008\" class=\"wp-image-11008\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/19-4-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/19-4-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/19-4-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/19-4-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/19-4.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/20-3-1024x683.jpg\" alt=\"\" data-id=\"11009\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/20-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11009\" class=\"wp-image-11009\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/20-3-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/20-3-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/20-3-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/20-3-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/20-3.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/21-3-1024x683.jpg\" alt=\"\" data-id=\"11010\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/21-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11010\" class=\"wp-image-11010\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/21-3-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/21-3-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/21-3-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/21-3-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/21-3.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/22-2-1024x683.jpg\" alt=\"\" data-id=\"11011\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/22-2.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11011\" class=\"wp-image-11011\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/22-2-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/22-2-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/22-2-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/22-2-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/22-2.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/23-2-1024x683.jpg\" alt=\"\" data-id=\"11012\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/23-2.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11012\" class=\"wp-image-11012\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/23-2-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/23-2-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/23-2-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/23-2-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/23-2.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/24-1-1024x683.jpg\" alt=\"\" data-id=\"11013\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/24-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11013\" class=\"wp-image-11013\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/24-1-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/24-1-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/24-1-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/24-1-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/24-1.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/25-1-1024x683.jpg\" alt=\"\" data-id=\"11014\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/25-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11014\" class=\"wp-image-11014\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/25-1-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/25-1-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/25-1-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/25-1-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/25-1.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/26-1-1024x683.jpg\" alt=\"\" data-id=\"11015\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/26-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11015\" class=\"wp-image-11015\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/26-1-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/26-1-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/26-1-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/26-1-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/26-1.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/27-1-1024x683.jpg\" alt=\"\" data-id=\"11016\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/27-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11016\" class=\"wp-image-11016\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/27-1-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/27-1-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/27-1-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/27-1-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/27-1.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/28-1024x683.jpg\" alt=\"\" data-id=\"11017\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/28.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11017\" class=\"wp-image-11017\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/28-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/28-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/28-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/28-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/28.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/29-1024x683.jpg\" alt=\"\" data-id=\"11018\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/29.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11018\" class=\"wp-image-11018\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/29-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/29-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/29-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/29-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/06\/29.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35 \u0e17\u0e35\u0e48 22 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2566 \u0e19\u0e32\u0e22\u0e18\u0e19\u0e34\u0e15 \u0e41\u0e17\u0e48\u0e19\u0e1b\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10991,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,10,7],"tags":[],"_links":{"self":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/10990"}],"collection":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/comments?post=10990"}],"version-history":[{"count":1,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/10990\/revisions"}],"predecessor-version":[{"id":11019,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/10990\/revisions\/11019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/media\/10991"}],"wp:attachment":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/media?parent=10990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/categories?post=10990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/tags?post=10990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}