{"id":11396,"date":"2023-08-10T15:27:07","date_gmt":"2023-08-10T08:27:07","guid":{"rendered":"https:\/\/ptl.ac.th\/web\/?p=11396"},"modified":"2023-08-10T15:27:07","modified_gmt":"2023-08-10T08:27:07","slug":"%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b9%80%e0%b8%89%e0%b8%a5%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%99%e0%b8%a1%e0%b8%9e","status":"publish","type":"post","link":"https:\/\/ptl.ac.th\/web\/2023\/08\/10\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b9%80%e0%b8%89%e0%b8%a5%e0%b8%b4%e0%b8%a1%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%99%e0%b8%a1%e0%b8%9e\/","title":{"rendered":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e42\u0e23\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 91 \u0e1e\u0e23\u0e23\u0e29\u0e32"},"content":{"rendered":"\n<p>\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35 \u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 \u0e19\u0e32\u0e22\u0e18\u0e19\u0e34\u0e15 \u0e41\u0e17\u0e48\u0e19\u0e1b\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e42\u0e23\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 91 \u0e1e\u0e23\u0e23\u0e29\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e30\u0e04\u0e23\u0e39 \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1f\u0e23\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 &#8211; 11 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 \u0e40\u0e27\u0e25\u0e32 09.30 \u0e19. &#8211; 14.00 \u0e19. \u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e42\u0e19\u0e23\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/1-4-1024x768.jpg\" alt=\"\" data-id=\"11397\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/1-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11397\" class=\"wp-image-11397\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/1-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/1-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/1-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/1-4-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/1-4.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/2-4-1024x768.jpg\" alt=\"\" data-id=\"11398\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/2-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11398\" class=\"wp-image-11398\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/2-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/2-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/2-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/2-4-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/2-4.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/3-4-1024x768.jpg\" alt=\"\" data-id=\"11399\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/3-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11399\" class=\"wp-image-11399\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/3-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/3-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/3-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/3-4-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/3-4.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/4-4-1024x768.jpg\" alt=\"\" data-id=\"11400\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/4-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11400\" class=\"wp-image-11400\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/4-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/4-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/4-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/4-4-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/4-4.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/5-4-1024x768.jpg\" alt=\"\" data-id=\"11401\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/5-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11401\" class=\"wp-image-11401\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/5-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/5-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/5-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/5-4-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/5-4.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/6-4-1024x768.jpg\" alt=\"\" data-id=\"11402\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/6-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11402\" class=\"wp-image-11402\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/6-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/6-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/6-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/6-4.jpg 1479w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/7-4-1024x768.jpg\" alt=\"\" data-id=\"11403\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/7-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11403\" class=\"wp-image-11403\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/7-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/7-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/7-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/7-4.jpg 1479w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/8-3-1024x768.jpg\" alt=\"\" data-id=\"11404\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/8-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11404\" class=\"wp-image-11404\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/8-3-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/8-3-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/8-3-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/8-3-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/8-3.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/9-3-1024x768.jpg\" alt=\"\" data-id=\"11405\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/9-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11405\" class=\"wp-image-11405\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/9-3-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/9-3-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/9-3-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/9-3-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/9-3.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/10-3-1024x768.jpg\" alt=\"\" data-id=\"11406\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/10-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11406\" class=\"wp-image-11406\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/10-3-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/10-3-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/10-3-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/10-3-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/10-3.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/11-3-1024x768.jpg\" alt=\"\" data-id=\"11407\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/11-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11407\" class=\"wp-image-11407\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/11-3-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/11-3-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/11-3-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/11-3-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/11-3.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/12-1-1024x768.jpg\" alt=\"\" data-id=\"11408\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/12-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11408\" class=\"wp-image-11408\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/12-1-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/12-1-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/12-1-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/12-1-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/12-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/13-1-1024x768.jpg\" alt=\"\" data-id=\"11409\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/13-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11409\" class=\"wp-image-11409\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/13-1-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/13-1-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/13-1-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/13-1-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/13-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/14-1-1024x768.jpg\" alt=\"\" data-id=\"11410\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/14-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11410\" class=\"wp-image-11410\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/14-1-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/14-1-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/14-1-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/14-1-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/14-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/15-1-1024x768.jpg\" alt=\"\" data-id=\"11411\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/15-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11411\" class=\"wp-image-11411\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/15-1-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/15-1-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/15-1-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/15-1-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/15-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/16-1-1024x768.jpg\" alt=\"\" data-id=\"11412\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/16-1.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11412\" class=\"wp-image-11412\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/16-1-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/16-1-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/16-1-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/16-1-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/16-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/17-1024x768.jpg\" alt=\"\" data-id=\"11413\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/17.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11413\" class=\"wp-image-11413\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/17-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/17-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/17-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/17-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/17.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/18-1024x768.jpg\" alt=\"\" data-id=\"11414\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/18.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11414\" class=\"wp-image-11414\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/18-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/18-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/18-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/18-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/18.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/19-1024x768.jpg\" alt=\"\" data-id=\"11415\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/19.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11415\" class=\"wp-image-11415\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/19-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/19-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/19-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/19-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/19.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/20-1024x768.jpg\" alt=\"\" data-id=\"11416\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/20.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=11416\" class=\"wp-image-11416\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/20-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/20-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/20-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/20-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2023\/08\/20.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35 \u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 \u0e19\u0e32\u0e22\u0e18\u0e19\u0e34\u0e15 \u0e41\u0e17\u0e48\u0e19\u0e1b\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11398,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,10,7],"tags":[],"_links":{"self":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/11396"}],"collection":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/comments?post=11396"}],"version-history":[{"count":1,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/11396\/revisions"}],"predecessor-version":[{"id":11417,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/11396\/revisions\/11417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/media\/11398"}],"wp:attachment":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/media?parent=11396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/categories?post=11396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/tags?post=11396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}