{"id":23608,"date":"2026-07-15T15:30:07","date_gmt":"2026-07-15T08:30:07","guid":{"rendered":"https:\/\/ptl.ac.th\/web\/?p=23608"},"modified":"2026-07-15T15:30:07","modified_gmt":"2026-07-15T08:30:07","slug":"%e0%b8%9e%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%a7%e0%b8%94%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%87-2","status":"publish","type":"post","link":"https:\/\/ptl.ac.th\/web\/2026\/07\/15\/%e0%b8%9e%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%a7%e0%b8%94%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%87-2\/","title":{"rendered":"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e20\u0e32\u0e04\u0e43\u0e15\u0e49"},"content":{"rendered":"\n<p><img loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\udccc\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tac\/1\/16\/1f4cc.png\">\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48 14 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2569 <img loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\u2728\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf4\/1\/16\/2728.png\">\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e0a\u0e19\u0e21\u0e4c\u0e28\u0e34\u0e01\u0e32\u0e19\u0e15\u0e4c \u0e41\u0e01\u0e49\u0e27\u0e01\u0e23\u0e30\u0e08\u0e48\u0e32\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e2a\u0e38\u0e19\u0e17\u0e23 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19 <img loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83c\udf89\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8c\/1\/16\/1f389.png\">\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e20\u0e32\u0e04\u0e43\u0e15\u0e49 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2569 \u0e23\u0e30\u0e14\u0e31\u0e1a(\u0e1b\u0e27\u0e0a.) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a (\u0e1b\u0e27\u0e2a.) <img loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\u2728\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf4\/1\/16\/2728.png\">\u0e42\u0e14\u0e22\u0e21\u0e35 \u0e14\u0e23.\u0e0a\u0e19\u0e30\u0e20\u0e23\u0e13\u0e4c \u0e2d\u0e37\u0e2d\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e07\u0e02\u0e25\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14 \u0e13 \u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e0a\u0e31\u0e49\u0e19 5 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25 \u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e07\u0e02\u0e25\u0e32 <img loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\ude4f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t80\/1\/16\/1f64f.png\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e0a\u0e19\u0e21\u0e4c\u0e28\u0e34\u0e01\u0e32\u0e19\u0e15\u0e4c \u0e41\u0e01\u0e49\u0e27\u0e01\u0e23\u0e30\u0e08\u0e48\u0e32\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e2a\u0e38\u0e19\u0e17\u0e23 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e17\u0e35\u0e21\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e08\u0e32\u0e01\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 -15 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2569 \u0e42\u0e14\u0e22\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e27\u0e0a. \u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e08\u0e25\u0e25\u0e35\u0e48\u0e1a\u0e2d\u0e25\u0e40\u0e1e\u0e04\u0e15\u0e34\u0e19\u0e08\u0e32\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e31\u0e1a\u0e1b\u0e30\u0e23\u0e14\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e1e\u0e23\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e21\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e31\u0e07\u0e02\u0e4c\u0e2b\u0e22\u0e14 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e42\u0e21\u0e40\u0e25\u0e01\u0e38\u0e25\u0e32\u0e23\u0e4c\u0e41\u0e01\u0e2a\u0e42\u0e15\u0e23\u0e42\u0e19\u0e21\u0e35\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e27\u0e2a. \u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e23\u0e34\u0e2a\u0e1b\u0e35\u0e49\u0e1a\u0e2d\u0e25\u0e41\u0e1b\u0e49\u0e07\u0e2a\u0e32\u0e04\u0e39\u0e15\u0e49\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e04\u0e15\u0e34\u0e19\u0e08\u0e32\u0e01\u0e41\u0e01\u0e19\u0e2a\u0e31\u0e1a\u0e1b\u0e30\u0e23\u0e14<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1012\" height=\"1024\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/1-8-1012x1024.jpg\" alt=\"\" data-id=\"23609\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/1-8.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23609\" class=\"wp-image-23609\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/1-8-1012x1024.jpg 1012w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/1-8-297x300.jpg 297w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/1-8-768x777.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/1-8.jpg 1108w\" sizes=\"(max-width: 1012px) 100vw, 1012px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/2-7-1024x768.jpg\" alt=\"\" data-id=\"23610\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/2-7.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23610\" class=\"wp-image-23610\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/2-7-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/2-7-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/2-7-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/2-7-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/2-7.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/3-8-1024x768.jpg\" alt=\"\" data-id=\"23611\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/3-8.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23611\" class=\"wp-image-23611\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/3-8-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/3-8-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/3-8-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/3-8-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/3-8.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"517\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/4-5-1024x517.jpg\" alt=\"\" data-id=\"23612\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/4-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23612\" class=\"wp-image-23612\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/4-5-1024x517.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/4-5-300x151.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/4-5-768x388.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/4-5-1536x776.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/4-5.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/5-5-1024x683.jpg\" alt=\"\" data-id=\"23613\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/5-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23613\" class=\"wp-image-23613\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/5-5-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/5-5-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/5-5-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/5-5-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/5-5.jpg 1776w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/6-5-1024x683.jpg\" alt=\"\" data-id=\"23614\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/6-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23614\" class=\"wp-image-23614\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/6-5-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/6-5-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/6-5-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/6-5-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/6-5.jpg 1776w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/7-5-1024x683.jpg\" alt=\"\" data-id=\"23615\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/7-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23615\" class=\"wp-image-23615\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/7-5-1024x683.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/7-5-300x200.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/7-5-768x512.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/7-5-1536x1024.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/7-5.jpg 1776w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"473\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/8-5-1024x473.jpg\" alt=\"\" data-id=\"23616\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/8-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23616\" class=\"wp-image-23616\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/8-5-1024x473.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/8-5-300x138.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/8-5-768x354.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/8-5-1536x709.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/8-5.jpg 1768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"572\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/9-5-1024x572.jpg\" alt=\"\" data-id=\"23617\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/9-5.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23617\" class=\"wp-image-23617\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/9-5-1024x572.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/9-5-300x168.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/9-5-768x429.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/9-5.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"557\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/10-4-1024x557.jpg\" alt=\"\" data-id=\"23618\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/10-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23618\" class=\"wp-image-23618\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/10-4-1024x557.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/10-4-300x163.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/10-4-768x417.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/10-4.jpg 1387w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"498\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/11-4-1024x498.jpg\" alt=\"\" data-id=\"23619\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/11-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23619\" class=\"wp-image-23619\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/11-4-1024x498.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/11-4-300x146.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/11-4-768x374.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/11-4-1536x747.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/11-4.jpg 1833w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/12-4-1024x768.jpg\" alt=\"\" data-id=\"23620\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/12-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23620\" class=\"wp-image-23620\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/12-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/12-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/12-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/12-4-1536x1152.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/12-4.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"620\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/13-4-1024x620.jpg\" alt=\"\" data-id=\"23621\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/13-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23621\" class=\"wp-image-23621\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/13-4-1024x620.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/13-4-300x182.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/13-4-768x465.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/13-4.jpg 1476w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/14-4-1024x768.jpg\" alt=\"\" data-id=\"23622\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/14-4.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23622\" class=\"wp-image-23622\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/14-4-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/14-4-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/14-4-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/14-4.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"480\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/15-3-1024x480.jpg\" alt=\"\" data-id=\"23623\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/15-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23623\" class=\"wp-image-23623\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/15-3-1024x480.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/15-3-300x141.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/15-3-768x360.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/15-3.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"542\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/16-3-1024x542.jpg\" alt=\"\" data-id=\"23624\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/16-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23624\" class=\"wp-image-23624\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/16-3-1024x542.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/16-3-300x159.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/16-3-768x407.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/16-3.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/17-3-1024x768.jpg\" alt=\"\" data-id=\"23625\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/17-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23625\" class=\"wp-image-23625\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/17-3-1024x768.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/17-3-300x225.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/17-3-768x576.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/17-3.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"624\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/18-3-1024x624.jpg\" alt=\"\" data-id=\"23626\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/18-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23626\" class=\"wp-image-23626\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/18-3-1024x624.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/18-3-300x183.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/18-3-768x468.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/18-3.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"701\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/19-3-1024x701.jpg\" alt=\"\" data-id=\"23627\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/19-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23627\" class=\"wp-image-23627\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/19-3-1024x701.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/19-3-300x205.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/19-3-768x526.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/19-3-1536x1051.jpg 1536w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/19-3.jpg 1546w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"718\" src=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/20-3-1024x718.jpg\" alt=\"\" data-id=\"23628\" data-full-url=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/20-3.jpg\" data-link=\"https:\/\/ptl.ac.th\/web\/?attachment_id=23628\" class=\"wp-image-23628\" srcset=\"https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/20-3-1024x718.jpg 1024w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/20-3-300x210.jpg 300w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/20-3-768x539.jpg 768w, https:\/\/ptl.ac.th\/wp-content\/uploads\/2026\/07\/20-3.jpg 1528w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e20\u0e32\u0e04\u0e43\u0e15 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23612,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12,11,10,7],"tags":[],"_links":{"self":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/23608"}],"collection":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/comments?post=23608"}],"version-history":[{"count":1,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/23608\/revisions"}],"predecessor-version":[{"id":23629,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/posts\/23608\/revisions\/23629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/media\/23612"}],"wp:attachment":[{"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/media?parent=23608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/categories?post=23608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ptl.ac.th\/web\/wp-json\/wp\/v2\/tags?post=23608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}